{"id":11100,"date":"2017-06-26T14:50:19","date_gmt":"2017-06-26T12:50:19","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/de\/?p=11100"},"modified":"2019-05-15T12:49:51","modified_gmt":"2019-05-15T10:49:51","slug":"gmail-wird-weniger-invasiv","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/","title":{"rendered":"Gmail wird weniger invasiv"},"content":{"rendered":"<p>Eine erfreuliche Nachricht gab es Ende vergangener Woche von Google: Der Internetriese will private Gmail-Nachrichten k\u00fcnftig nicht mehr zu Werbezwecken \u201emitlesen\u201c.<\/p>\n<p>Das k\u00fcndigte Diane Green, die Mitgr\u00fcnderin und langj\u00e4hrige Chefin von VMware und mittlerweile verantwortlich f\u00fcr Googles Public-Cloud-Sparte, <a href=\"https:\/\/blog.google\/products\/gmail\/g-suite-gains-traction-in-the-enterprise-g-suites-gmail-and-consumer-gmail-to-more-closely-align\/\">im Firmenblog<\/a> an. Die kostenlose Consumer-Version von Gmail soll in dieser Hinsicht an das kommerzielle und grunds\u00e4tzlich werbefreie Gmail aus der Cloud-Programmsammlung G Suite (vormals Google Apps for Business) angeglichen werden.<\/p>\n<p>Werbung wird es im Consumer-Gmail zwar weiterhin geben, allerdings kann der Nutzer sie k\u00fcnftig wie f\u00fcr die \u00fcbrigen Google-Dienste zentral in den <a href=\"https:\/\/myaccount.google.com\/\">Google-Kontoeinstellungen<\/a> regeln und beispielsweise die Personalisierung von Anzeigen abschalten. Algorithmen von Google werden auch weiterhin den Inhalt von Gmail-Nachrichten erfassen, aber nur f\u00fcr <a href=\"https:\/\/research.googleblog.com\/2017\/05\/efficient-smart-reply-now-for-gmail.html\">Komfortfunktionen wie \u201eSmart Reply\u201c<\/a>. Add-ons sollen optional auch Funktionen wie Bezahlen oder Rechnungen stellen direkt aus Gmail heraus erm\u00f6glichen.<\/p>\n<p>Marktbegleiter wie Microsoft hatten Google seit dem Start von Gmail \u2013 in Deutschland hie\u00df der Dienst aus markenrechtlichen Gr\u00fcnden lange offiziell Google Mail \u2013 im Jahr 2004 daf\u00fcr kritisiert, dass Inhalte zwecks Personalisierung der Werbung maschinengelesen wurden. Den Erfolg von Gmail konnte das allerdings kaum aufhalten; nach Angaben von Google nutzen den Service mehr als 1,2 Milliarden Menschen rund um den Globus.<\/p>\n<p>Die Nutzungszahlen von Gmail (dazu kommen noch die Postf\u00e4cher bei den rund drei Millionen Firmen, die f\u00fcr die G Suite zahlen) und seine angek\u00fcndigte Weiterentwicklung unterstreichen eindrucksvoll, dass die E-Mail trotz ihres zwischenzeitlich immer wieder heraufbeschworenen Todes quicklebendig und als Kanal der elektronischen Kommunikation trotz neuer Tools nicht wegzudenken ist.<\/p>\n<p>Unternehmen m\u00fcssen E-Mail nat\u00fcrlich aus vielf\u00e4ltigen Gr\u00fcnden sehr viel sorgf\u00e4ltiger nutzen als Verbraucher. Der Managed Cloud Service <a href=\"https:\/\/www.retarus.com\/de\/products\/retarus-email-security\/\">Retarus E-Mail-Secu\u00adrity<\/a> ist eine Komplett\u00adl\u00f6\u00adsung f\u00fcr viren- und spam\u00adfreie E-Mail-Kommu\u00adni\u00adka\u00adtion mit umfang\u00adrei\u00adchen Funk\u00adtio\u00adnen bis hin zur <a href=\"https:\/\/www.retarus.com\/de\/products\/retarus-patient-zero-detection\/\">neuen Pati\u00adent Zero Detec\u00adtion<\/a>, die infi\u00adzierte Nach\u00adrich\u00adten im Post\u00adein\u00adgang nach\u00adtr\u00e4g\u00adlich entdeckt und Unter\u00adneh\u00admen dadurch vor hohen Folge\u00adkos\u00adten sch\u00fct\u00adzen kann. Mehr dar\u00fcber erfah\u00adren Sie <a href=\"https:\/\/www.retarus.com\/de\/products\/retarus-email-security\/\">hier<\/a> oder direkt bei Ihrem <a href=\"https:\/\/www.retarus.com\/de\/contact\/\">Retarus-Ansprech\u00adpart\u00adner vor Ort<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google will private Gmail-Nachrichten k\u00fcnftig nicht mehr zu Werbezwecken \u201emitlesen\u201c.<\/p>\n","protected":false},"author":14,"featured_media":11101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_s2mail":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-11100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cloud"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gmail wird weniger invasiv - Retarus Corporate Blog - DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gmail wird weniger invasiv\" \/>\n<meta property=\"og:description\" content=\"Google will private Gmail-Nachrichten k\u00fcnftig nicht mehr zu Werbezwecken \u201emitlesen\u201c.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - DE\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-26T12:50:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T10:49:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/06\/gmail_icon-730x410px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thomas Cloer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Cloer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/\"},\"author\":{\"name\":\"Thomas Cloer\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"headline\":\"Gmail wird weniger invasiv\",\"datePublished\":\"2017-06-26T12:50:19+00:00\",\"dateModified\":\"2019-05-15T10:49:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/\"},\"wordCount\":361,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/06\\\/gmail_icon-730x410px.png\",\"articleSection\":[\"Cloud\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/\",\"name\":\"Gmail wird weniger invasiv - Retarus Corporate Blog - DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/06\\\/gmail_icon-730x410px.png\",\"datePublished\":\"2017-06-26T12:50:19+00:00\",\"dateModified\":\"2019-05-15T10:49:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/06\\\/gmail_icon-730x410px.png\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/06\\\/gmail_icon-730x410px.png\",\"width\":730,\"height\":410,\"caption\":\"Gmail icon, 730 x 410 px PNG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/gmail-wird-weniger-invasiv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gmail wird weniger invasiv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\",\"name\":\"Retarus Corporate Blog - DE\",\"description\":\"Immer up-to-date\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\",\"name\":\"Thomas Cloer\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/author\\\/thomasc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gmail wird weniger invasiv - Retarus Corporate Blog - DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/","og_locale":"de_DE","og_type":"article","og_title":"Gmail wird weniger invasiv","og_description":"Google will private Gmail-Nachrichten k\u00fcnftig nicht mehr zu Werbezwecken \u201emitlesen\u201c.","og_url":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/","og_site_name":"Retarus Corporate Blog - DE","article_published_time":"2017-06-26T12:50:19+00:00","article_modified_time":"2019-05-15T10:49:51+00:00","og_image":[{"width":730,"height":410,"url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/06\/gmail_icon-730x410px.png","type":"image\/png"}],"author":"Thomas Cloer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thomas Cloer","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/"},"author":{"name":"Thomas Cloer","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"headline":"Gmail wird weniger invasiv","datePublished":"2017-06-26T12:50:19+00:00","dateModified":"2019-05-15T10:49:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/"},"wordCount":361,"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/06\/gmail_icon-730x410px.png","articleSection":["Cloud"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/","url":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/","name":"Gmail wird weniger invasiv - Retarus Corporate Blog - DE","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/06\/gmail_icon-730x410px.png","datePublished":"2017-06-26T12:50:19+00:00","dateModified":"2019-05-15T10:49:51+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/06\/gmail_icon-730x410px.png","contentUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/06\/gmail_icon-730x410px.png","width":730,"height":410,"caption":"Gmail icon, 730 x 410 px PNG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/de\/gmail-wird-weniger-invasiv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Gmail wird weniger invasiv"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/de\/#website","url":"https:\/\/www.retarus.com\/blog\/de\/","name":"Retarus Corporate Blog - DE","description":"Immer up-to-date","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5","name":"Thomas Cloer","url":"https:\/\/www.retarus.com\/blog\/de\/author\/thomasc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/11100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=11100"}],"version-history":[{"count":3,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/11100\/revisions"}],"predecessor-version":[{"id":12915,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/11100\/revisions\/12915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media\/11101"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=11100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=11100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=11100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}