{"id":11501,"date":"2017-12-21T14:04:54","date_gmt":"2017-12-21T13:04:54","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/de\/?p=11501"},"modified":"2021-02-17T10:25:59","modified_gmt":"2021-02-17T09:25:59","slug":"wir-haetten-da-was-lieber-porsche-betriebsrat","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/","title":{"rendered":"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat"},"content":{"rendered":"<p>Der Betriebsrat von Porsche m\u00f6chte seine Belegschaft in der Freizeit von beruflichen E-Mails verschont sehen, um Burnouts vorzubeugen. Retarus hat daf\u00fcr die passende L\u00f6sung.<\/p>\n<p>Porsche-Betriebsratschef Uwe H\u00fcck wolle aus Sorge vor Burnout in der Belegschaft neue E-Mail-Regeln einf\u00fchren, <a href=\"https:\/\/www.handelsblatt.com\/unternehmen\/management\/porsche-betriebsrat-hueck-will-e-mails-nach-feierabend-loeschen-lassen\/20736680.html\">berichtete die Deutsche Presse-Agentur<\/a>. Um die Arbeitsbelastung zu senken, sollten Mailkonten von Mitarbeitern im Zeitraum zwischen 19 Uhr und 6 Uhr sowie am Wochenende und im Urlaub gesperrt werden, sagte H\u00fcck demnach in Stuttgart: \u201eAbends noch Mails vom Chef lesen und beantworten, ist unbezahlte Arbeitszeit, die den Stress erh\u00f6ht &#8211; das geht gar nicht.\u201c<\/p>\n<p>Ginge es nach H\u00fcck, dann w\u00fcrden E-Mails au\u00dferhalb der Arbeitszeit an den Absender zur\u00fcckbouncen und im Posteingang des Empf\u00e4ngers gel\u00f6scht respektive gar nicht angezeigt. Diese Regelung sollte nur f\u00fcr Tarifmitarbeiter gelten, F\u00fchrungskr\u00e4fte blieben au\u00dfen vor, hei\u00dft es weiter. Mit einer solchen Regelung w\u00fcrde Porsche jedenfalls einen Schritt weiter gehen als andere Automotive-Player. VW hat laut dpa zwar eine Mailkonten-Sperrung \u00fcber Nacht, morgens ist die angekommene Post aber zu lesen. Daimler wiederum biete seinen Mitarbeitern an, dass sie ihre Mails auf Wunsch im Urlaub automatisch l\u00f6schen lassen k\u00f6nnten.<\/p>\n<p><a href=\"https:\/\/www.retarus.com\/de\/products\/retarus-email-security\/\">Retarus E-Mail Security<\/a> bietet bereits als Erg\u00e4nzung zum Essential-Protection-Paket\u00a0<a href=\"https:\/\/www.retarus.com\/de\/tech-products\/email-security-and-compliance-services\/\">die Zusatzfunktion \u201eQuiet Time\u201c<\/a>. Diese erm\u00f6glicht es, Zeitintervalle festzulegen, in denen Mitarbeitern keine externen E-Mails zugestellt werden \u2013 zum Beispiel Freizeiten und Wochenenden. Es lassen sich auch Zeitintervalle festlegen, in denen an kein Postfach E-Mails zugestellt werden, um den E-Mail Server problemlos warten zu k\u00f6nnen.<\/p>\n<p>Quiet Time bietet folgende M\u00f6glichkeiten:<\/p>\n<ul>\n<li>Konfiguration E-Mail-freier Zeitintervalle (externe E-Mails)<\/li>\n<li>Individuelle Einstellungen f\u00fcr unterschiedliche Anwenderprofile<\/li>\n<li>Sichere Zwischenspeicherung der E-Mails in den Retarus Rechenzentren<\/li>\n<li>Automatische Zustellung der E-Mails nach Ablauf der definierten Zeitintervalle<\/li>\n<li>Durchleitfunktion f\u00fcr E-Mails mit hoher Priorit\u00e4t<\/li>\n<li>Notfall-Button f\u00fcr die sofortige Zustellung von E-Mails in E-Mail-freien Zeitr\u00e4umen<\/li>\n<\/ul>\n<p>Jetzt w\u00fcnschen wir Ihnen aber erst einmal erholsame Feiertage, Frohe Weihnachten und den sprichw\u00f6rtlich guten Rutsch ins Neue Jahr. Und zur Einstimmung entf\u00fchren wir Sie <a href=\"https:\/\/www.retarus.com\/blog\/de\/get-into-the-swing-of-christmas-retarus-winter-wonderland\/\">ins Retarus Winter Wonderland<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Betriebsrat von Porsche m\u00f6chte seine Belegschaft in der Freizeit von beruflichen E-Mails verschont sehen, um Burnouts vorzubeugen. Retarus hat daf\u00fcr die passende L\u00f6sung.<\/p>\n","protected":false},"author":14,"featured_media":11503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_s2mail":"","footnotes":""},"categories":[51,20],"tags":[159],"class_list":["post-11501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-trends","category-product-news","tag-email-security"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wir h\u00e4tten da was, lieber Porsche-Betriebsrat - Retarus Corporate Blog - DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat\" \/>\n<meta property=\"og:description\" content=\"Der Betriebsrat von Porsche m\u00f6chte seine Belegschaft in der Freizeit von beruflichen E-Mails verschont sehen, um Burnouts vorzubeugen. Retarus hat daf\u00fcr die passende L\u00f6sung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - DE\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-21T13:04:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-17T09:25:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/12\/dnd_shutterstock_719300440.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Cloer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Cloer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/\"},\"author\":{\"name\":\"Thomas Cloer\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"headline\":\"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat\",\"datePublished\":\"2017-12-21T13:04:54+00:00\",\"dateModified\":\"2021-02-17T09:25:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/\"},\"wordCount\":347,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/12\\\/dnd_shutterstock_719300440.jpg\",\"keywords\":[\"Email Security\"],\"articleSection\":[\"Business Trends\",\"Product News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/\",\"name\":\"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat - Retarus Corporate Blog - DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/12\\\/dnd_shutterstock_719300440.jpg\",\"datePublished\":\"2017-12-21T13:04:54+00:00\",\"dateModified\":\"2021-02-17T09:25:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/12\\\/dnd_shutterstock_719300440.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/12\\\/dnd_shutterstock_719300440.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Do not disturb, Bitte nicht st\u00f6ren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wir-haetten-da-was-lieber-porsche-betriebsrat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\",\"name\":\"Retarus Corporate Blog - DE\",\"description\":\"Immer up-to-date\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\",\"name\":\"Thomas Cloer\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/author\\\/thomasc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat - Retarus Corporate Blog - DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/","og_locale":"de_DE","og_type":"article","og_title":"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat","og_description":"Der Betriebsrat von Porsche m\u00f6chte seine Belegschaft in der Freizeit von beruflichen E-Mails verschont sehen, um Burnouts vorzubeugen. Retarus hat daf\u00fcr die passende L\u00f6sung.","og_url":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/","og_site_name":"Retarus Corporate Blog - DE","article_published_time":"2017-12-21T13:04:54+00:00","article_modified_time":"2021-02-17T09:25:59+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/12\/dnd_shutterstock_719300440.jpg","type":"image\/jpeg"}],"author":"Thomas Cloer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thomas Cloer","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/"},"author":{"name":"Thomas Cloer","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"headline":"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat","datePublished":"2017-12-21T13:04:54+00:00","dateModified":"2021-02-17T09:25:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/"},"wordCount":347,"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/12\/dnd_shutterstock_719300440.jpg","keywords":["Email Security"],"articleSection":["Business Trends","Product News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/","url":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/","name":"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat - Retarus Corporate Blog - DE","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/12\/dnd_shutterstock_719300440.jpg","datePublished":"2017-12-21T13:04:54+00:00","dateModified":"2021-02-17T09:25:59+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/12\/dnd_shutterstock_719300440.jpg","contentUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/12\/dnd_shutterstock_719300440.jpg","width":1920,"height":1080,"caption":"Do not disturb, Bitte nicht st\u00f6ren"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Wir h\u00e4tten da was, lieber Porsche-Betriebsrat"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/de\/#website","url":"https:\/\/www.retarus.com\/blog\/de\/","name":"Retarus Corporate Blog - DE","description":"Immer up-to-date","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5","name":"Thomas Cloer","url":"https:\/\/www.retarus.com\/blog\/de\/author\/thomasc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/11501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=11501"}],"version-history":[{"count":4,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/11501\/revisions"}],"predecessor-version":[{"id":14988,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/11501\/revisions\/14988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media\/11503"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=11501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=11501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=11501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}