{"id":1256,"date":"2016-02-03T10:52:25","date_gmt":"2016-02-03T08:52:25","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/de\/?p=1256"},"modified":"2021-04-23T12:10:02","modified_gmt":"2021-04-23T10:10:02","slug":"e-mail-muss-wieder-spass-machen","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/","title":{"rendered":"E-Mail muss wieder Spa\u00df machen!"},"content":{"rendered":"<p>E-Mail-Kommunikation macht im Gesch\u00e4ftsleben schon lange keinen Spa\u00df mehr. Ein Grund daf\u00fcr ist die immer st\u00e4rkere Digitalisierung der Arbeitswelt. Vielf\u00e4ltige digitale Angriffsmechanismen, wie Viren, Spam oder Phishing, erschweren Unternehmen die E-Mail-Nutzung zus\u00e4tzlich. Zudem prasselt t\u00e4glich eine Unmenge an E-Mails auf Verantwortliche eines Unternehmens ein. Die permanente Erreichbarkeit via E-Mail ist allerdings nicht nur zeitintensiv, sondern verursacht auch Stress. Doch was dagegen tun?<\/p>\n<h2>E-Mail als Stressfaktor<\/h2>\n<p>Smartphones und Tablets sorgen heute daf\u00fcr, dass Chefs und Angestellte rund um die Uhr und \u00fcberall online sind \u2013 und damit auch au\u00dferhalb der regul\u00e4ren Arbeitszeit erreichbar bleiben. Die Folge: Gesch\u00e4ftsleute sind zunehmend \u00fcberlastet, Arbeitsausf\u00e4lle aufgrund psychischer Erkrankungen nehmen drastisch zu. Politik und Wirtschaft haben deshalb bereits erste Initiativen f\u00fcr ein Mail-Verbot nach Feierabend ins Leben gerufen. So hat sich das <a href=\"https:\/\/www.sueddeutsche.de\/karriere\/neue-richtlinie-im-bundesarbeitsministerium-geringstmoeglicher-eingriff-in-die-freizeit-1.1758132\" target=\"_blank\" rel=\"noopener noreferrer\">Bundesarbeitsministerium<\/a> bereits 2013 dazu verpflichtet, Mitarbeiter nur noch in absoluten Ausnahmef\u00e4llen in ihrer Freizeit per Anruf oder E-Mail zu st\u00f6ren. Bei VW werden mittlerweile bereits eine halbe Stunde nach Dienstschluss keine E-Mails mehr zugestellt. Die Deutsche Telekom, E.on, Puma und BMW haben \u00e4hnliche Beschr\u00e4nkungen festgelegt. Auch Bundesarbeitsministerin Andrea Nahles pr\u00fcft aktuell eine <a href=\"https:\/\/www.zeit.de\/politik\/deutschland\/2014-08\/nahles-will-anti-stress-verordnung\" target=\"_blank\" rel=\"noopener noreferrer\">Anti-Stress-Verordnung<\/a> auf Bundesebene.<\/p>\n<h2>Mit Retarus Quiet Time den Feierabend genie\u00dfen<\/h2>\n<p><a href=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2016\/02\/Retarus_Karikatur.jpg\"><img decoding=\"async\" class=\" wp-image-1257 alignleft\" src=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2016\/02\/Retarus_Karikatur-300x195.jpg\" alt=\"Retarus_Karikatur\" width=\"328\" height=\"213\"><\/a>Erste L\u00f6sungen, mit denen sich der E-Mail-Stress deutlich reduzieren l\u00e4sst, gibt es bereits. So lassen sich zum Beispiel \u00fcber das Retarus Feature \u201e<a href=\"https:\/\/www.retarus.com\/de\/tech-products\/retarus-email-security\/\" target=\"_blank\" rel=\"noopener noreferrer\">Quiet Time<\/a>\u201c flexible Zeitintervalle als Ruhezeiten definieren, wie Urlaube oder Wochenenden. Innerhalb dieser Zeitr\u00e4ume werden Mitarbeitern dann keine externen E-Mails zugestellt. Eingehende Nachrichten werden stattdessen in den Retarus-eigenen Rechenzentren zwischengespeichert. Nach Ablauf der festgelegten Zeitintervalle erhalten die Anwender automatisch alle bis dahin zur\u00fcckgehaltenen Nachrichten. Durchleitfunktionen f\u00fcr E-Mails mit hoher Priorit\u00e4t stellen zudem sicher, dass Nachrichten hoher Wichtigkeit nicht blockiert werden.<\/p>\n<h2>Stressreduzierung dank Retarus Inbox Assist<\/h2>\n<p>Speziell f\u00fcr F\u00fchrungskr\u00e4fte, die \u00fcber Assistenzen verf\u00fcgen, aber mehr Privatsph\u00e4re ben\u00f6tigen, eignet sich zudem die Funktion \u201e<a href=\"https:\/\/www.retarus.com\/de\/tech-products\/retarus-email-security\/\" target=\"_blank\" rel=\"noopener noreferrer\">Inbox Assist<\/a>\u201c von Retarus. Diese regelt den eingehenden E-Mail-Verkehr und stellt private E-Mails oder VIP-Nachrichten ausschlie\u00dflich dem adressierten Empf\u00e4nger zu, w\u00e4hrend normale Gesch\u00e4ftskorrespondenz automatisch an die Assistenz weitergeleitet wird. So erhalten Gesch\u00e4ftsf\u00fchrer, Abteilungsleiter und andere F\u00fchrungskr\u00e4fte nicht nur die erw\u00fcnschte Privatsph\u00e4re, sie werden auch von weniger kritischer Korrespondenz entlastet. Die Inbox wird weiterhin von der Assistenz vorsortiert und bearbeitet, ohne dass diese auf die Mailbox des Vorgesetzten zugreifen muss.<\/p>\n<h2>Weniger Stress bei maximaler Sicherheit<\/h2>\n<p>Auch die IT-Abteilungen stellt die gesch\u00e4ftliche E-Mail-Kommunikation vor gro\u00dfe Herausforderungen. Denn die E-Mail ist ein von Angreifern gern genutztes Einfallstor f\u00fcr Spam, Phishing, Viren und andere Malware. Auch die private Nutzung gesch\u00e4ftlicher Mail-Clients sowie der Zugriff \u00fcber private Smartphones oder Tablets, etwa im Home Office, bergen ein erh\u00f6htes Sicherheitsrisiko. Um den Austausch von sensiblen Daten entsprechend abzusichern und das Unternehmen umfassend vor Cyberangriffen zu sch\u00fctzen, ist die Verwendung verl\u00e4sslicher Sicherheitssysteme unabdingbar. Zudem sind Unternehmen gefordert, klare Regeln im Umgang mit Kommunikationsmitteln zu schaffen und ihre Mitarbeiter in entsprechenden Schulungen f\u00fcr diese Problematik zu sensibilisieren. <a href=\"https:\/\/www.retarus.com\/de\/products\/retarus-email-security\/\" target=\"_blank\" rel=\"noopener noreferrer\">Retarus E-Mail-Security<\/a> bietet daher nicht nur wertvolle Unterst\u00fctzung, um den Stressfaktor \u201eE-Mail-Kommunikation\u201c so gering wie m\u00f6glich zu halten, sondern helfen auch bei der Realisierung einer umfassenden E-Mail-Sicherheits-Strategie.<\/p>\n<p>Mehr \u00fcber Retarus E-Mail Security erfahren Sie <a href=\"https:\/\/www.retarus.com\/de\/services\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> oder direkt bei <a href=\"https:\/\/www.retarus.com\/de\/contact\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ihren Retarus Ansprechpartnern vor Ort<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?<\/p>\n","protected":false},"author":11,"featured_media":342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_s2mail":"","footnotes":""},"categories":[51],"tags":[159,206,208],"class_list":["post-1256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-trends","tag-email-security","tag-retarus-inbox-assist","tag-stress"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>E-Mail muss wieder Spa\u00df machen<\/title>\n<meta name=\"description\" content=\"Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-Mail muss wieder Spa\u00df machen!\" \/>\n<meta property=\"og:description\" content=\"Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - DE\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-03T08:52:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-23T10:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/06\/Mann_Computer_Handy_03_680x384.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabrina Hiller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabrina Hiller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/\"},\"author\":{\"name\":\"Sabrina Hiller\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/b52ddf77ed41a8431c9b47c4d18942d7\"},\"headline\":\"E-Mail muss wieder Spa\u00df machen!\",\"datePublished\":\"2016-02-03T08:52:25+00:00\",\"dateModified\":\"2021-04-23T10:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/\"},\"wordCount\":555,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/06\\\/Mann_Computer_Handy_03_680x384.jpg\",\"keywords\":[\"Email Security\",\"Retarus Inbox Assist\",\"Stress\"],\"articleSection\":[\"Business Trends\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/\",\"name\":\"E-Mail muss wieder Spa\u00df machen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/06\\\/Mann_Computer_Handy_03_680x384.jpg\",\"datePublished\":\"2016-02-03T08:52:25+00:00\",\"dateModified\":\"2021-04-23T10:10:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/b52ddf77ed41a8431c9b47c4d18942d7\"},\"description\":\"Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/06\\\/Mann_Computer_Handy_03_680x384.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/06\\\/Mann_Computer_Handy_03_680x384.jpg\",\"width\":680,\"height\":384},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/e-mail-muss-wieder-spass-machen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-Mail muss wieder Spa\u00df machen!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\",\"name\":\"Retarus Corporate Blog - DE\",\"description\":\"Immer up-to-date\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/b52ddf77ed41a8431c9b47c4d18942d7\",\"name\":\"Sabrina Hiller\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/author\\\/shiller\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"E-Mail muss wieder Spa\u00df machen","description":"Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/","og_locale":"de_DE","og_type":"article","og_title":"E-Mail muss wieder Spa\u00df machen!","og_description":"Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?","og_url":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/","og_site_name":"Retarus Corporate Blog - DE","article_published_time":"2016-02-03T08:52:25+00:00","article_modified_time":"2021-04-23T10:10:02+00:00","og_image":[{"width":680,"height":384,"url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/06\/Mann_Computer_Handy_03_680x384.jpg","type":"image\/jpeg"}],"author":"Sabrina Hiller","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sabrina Hiller","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/"},"author":{"name":"Sabrina Hiller","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/b52ddf77ed41a8431c9b47c4d18942d7"},"headline":"E-Mail muss wieder Spa\u00df machen!","datePublished":"2016-02-03T08:52:25+00:00","dateModified":"2021-04-23T10:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/"},"wordCount":555,"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/06\/Mann_Computer_Handy_03_680x384.jpg","keywords":["Email Security","Retarus Inbox Assist","Stress"],"articleSection":["Business Trends"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/","url":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/","name":"E-Mail muss wieder Spa\u00df machen","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/06\/Mann_Computer_Handy_03_680x384.jpg","datePublished":"2016-02-03T08:52:25+00:00","dateModified":"2021-04-23T10:10:02+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/b52ddf77ed41a8431c9b47c4d18942d7"},"description":"Die Bew\u00e4ltigung der E-Mail-Flut kostet nicht nur viel Zeit, sondern ist oft auch nervenaufreibend. Doch was dagegen tun?","breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/06\/Mann_Computer_Handy_03_680x384.jpg","contentUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/06\/Mann_Computer_Handy_03_680x384.jpg","width":680,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/de\/e-mail-muss-wieder-spass-machen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"E-Mail muss wieder Spa\u00df machen!"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/de\/#website","url":"https:\/\/www.retarus.com\/blog\/de\/","name":"Retarus Corporate Blog - DE","description":"Immer up-to-date","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/b52ddf77ed41a8431c9b47c4d18942d7","name":"Sabrina Hiller","url":"https:\/\/www.retarus.com\/blog\/de\/author\/shiller\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/1256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=1256"}],"version-history":[{"count":5,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/1256\/revisions"}],"predecessor-version":[{"id":15268,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/1256\/revisions\/15268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media\/342"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=1256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=1256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=1256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}