{"id":14161,"date":"2020-08-26T09:52:57","date_gmt":"2020-08-26T07:52:57","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/de\/?p=14161"},"modified":"2020-08-26T11:19:33","modified_gmt":"2020-08-26T09:19:33","slug":"messi-per-fax","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/","title":{"rendered":"Messi per Fax"},"content":{"rendered":"\n<p>Sch\u00f6n, wenn man einmal <a href=\"https:\/\/www.spiegel.de\/sport\/fussball\/lionel-messi-will-fc-barcelona-verlassen-der-juengste-tag-ist-gekommen-a-dae3eaa4-7fd1-49a6-8b46-d39a609db158\" target=\"_blank\" rel=\"noreferrer noopener\">nicht selbst erkl\u00e4ren<\/a> muss, warum Fax auch im Jahr 2020 nicht tot, anachronistisch oder hinterw\u00e4ldlerisch ist. Sondern f\u00fcr manch wichtige Kommunikation immer noch der Kanal der Wahl.<\/p>\n\n\n\n<p>Mehr \u00fcber die Retarus Communication Platform mit ihren <a href=\"https:\/\/www.retarus.com\/de\/services\/fax\/\">Cloud Fax Services<\/a> erfahren Sie auf unserer Webseite oder direkt von Ihrem <a href=\"https:\/\/www.retarus.com\/de\/contact\/\">Ansprechpartner vor Ort<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sch\u00f6n, wenn man einmal nicht selbst erkl\u00e4ren muss, warum Fax auch im Jahr 2020 nicht tot, anachronistisch oder hinterw\u00e4ldlerisch ist. Sondern f\u00fcr manch wichtige Kommunikation immer noch der Kanal der Wahl.<\/p>\n","protected":false},"author":14,"featured_media":14162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_s2mail":"","footnotes":""},"categories":[334,7],"tags":[],"class_list":["post-14161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ref-fax","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Messi per Fax - Retarus Corporate Blog - DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messi per Fax\" \/>\n<meta property=\"og:description\" content=\"Sch\u00f6n, wenn man einmal nicht selbst erkl\u00e4ren muss, warum Fax auch im Jahr 2020 nicht tot, anachronistisch oder hinterw\u00e4ldlerisch ist. Sondern f\u00fcr manch wichtige Kommunikation immer noch der Kanal der Wahl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - DE\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T07:52:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-26T09:19:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2020\/08\/messi-fax-spiegel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thomas Cloer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Cloer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/\"},\"author\":{\"name\":\"Thomas Cloer\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"headline\":\"Messi per Fax\",\"datePublished\":\"2020-08-26T07:52:57+00:00\",\"dateModified\":\"2020-08-26T09:19:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/\"},\"wordCount\":60,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/08\\\/messi-fax-spiegel.png\",\"articleSection\":[\"Fax\",\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/\",\"name\":\"Messi per Fax - Retarus Corporate Blog - DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/08\\\/messi-fax-spiegel.png\",\"datePublished\":\"2020-08-26T07:52:57+00:00\",\"dateModified\":\"2020-08-26T09:19:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/08\\\/messi-fax-spiegel.png\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/08\\\/messi-fax-spiegel.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/messi-per-fax\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messi per Fax\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\",\"name\":\"Retarus Corporate Blog - DE\",\"description\":\"Immer up-to-date\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\",\"name\":\"Thomas Cloer\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/author\\\/thomasc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Messi per Fax - Retarus Corporate Blog - DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/","og_locale":"de_DE","og_type":"article","og_title":"Messi per Fax","og_description":"Sch\u00f6n, wenn man einmal nicht selbst erkl\u00e4ren muss, warum Fax auch im Jahr 2020 nicht tot, anachronistisch oder hinterw\u00e4ldlerisch ist. Sondern f\u00fcr manch wichtige Kommunikation immer noch der Kanal der Wahl.","og_url":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/","og_site_name":"Retarus Corporate Blog - DE","article_published_time":"2020-08-26T07:52:57+00:00","article_modified_time":"2020-08-26T09:19:33+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2020\/08\/messi-fax-spiegel.png","type":"image\/png"}],"author":"Thomas Cloer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thomas Cloer"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/"},"author":{"name":"Thomas Cloer","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"headline":"Messi per Fax","datePublished":"2020-08-26T07:52:57+00:00","dateModified":"2020-08-26T09:19:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/"},"wordCount":60,"commentCount":0,"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2020\/08\/messi-fax-spiegel.png","articleSection":["Fax","News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/","url":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/","name":"Messi per Fax - Retarus Corporate Blog - DE","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2020\/08\/messi-fax-spiegel.png","datePublished":"2020-08-26T07:52:57+00:00","dateModified":"2020-08-26T09:19:33+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2020\/08\/messi-fax-spiegel.png","contentUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2020\/08\/messi-fax-spiegel.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/de\/messi-per-fax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Messi per Fax"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/de\/#website","url":"https:\/\/www.retarus.com\/blog\/de\/","name":"Retarus Corporate Blog - DE","description":"Immer up-to-date","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5","name":"Thomas Cloer","url":"https:\/\/www.retarus.com\/blog\/de\/author\/thomasc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/14161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=14161"}],"version-history":[{"count":4,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/14161\/revisions"}],"predecessor-version":[{"id":14166,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/14161\/revisions\/14166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media\/14162"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=14161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=14161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=14161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}