{"id":15089,"date":"2021-03-19T15:04:42","date_gmt":"2021-03-19T14:04:42","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/de\/?p=15089"},"modified":"2021-03-22T12:59:15","modified_gmt":"2021-03-22T11:59:15","slug":"kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/","title":{"rendered":"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Millionen von Besch\u00e4ftigten beziehen in Folge der Corona-Pandemie derzeit Kurzarbeitergeld \u2013 so viele wie <a href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/2603\/umfrage\/entwicklung-des-bestands-an-kurzarbeitern\/\">nie zuvor<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch viele Arbeitgeber stehen dabei vor bisher unbekannten Herausforderungen: Eine davon betrifft den Nachweis \u00fcber die (reduzierten) Arbeitszeiten ihrer Angestellten. Von der Bundesagentur f\u00fcr Arbeit hei\u00dft es dazu <a href=\"https:\/\/www.arbeitsagentur.de\/unternehmen\/corona-virus-informationen-fuer-unternehmen-zum-kurzarbeitergeld\" target=\"_blank\" rel=\"noreferrer noopener\">w\u00f6rtlich<\/a>: \u201eW\u00e4hrend der Kurzarbeit sind Arbeitszeitnachweise der betroffenen Arbeitnehmer\/innen zu f\u00fchren. Vorlagen daf\u00fcr gibt es nicht [sic!]. Zu erfassen ist in Stunden, wann die\/der Arbeitnehmer\/in tats\u00e4chlich gearbeitet hat (\u2026) und wann Kurzarbeit war.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-nachweis-f-r-mitarbeiter-im-home-office-in-der-praxis-schwierig\">Nachweis f\u00fcr Mitarbeiter im Home Office in der Praxis schwierig<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie der Nachweis im Falle einer Pr\u00fcfung zu erbringen ist, liegt also nicht zuletzt im Verantwortungsbereich der Unternehmen. Arbeitsrechtsexperten mahnen schon seit Beginn der Pandemie, dass es gerade bei Home Office oder bei Vertrauensarbeitszeit-Modellen \u201e<a href=\"https:\/\/www.spiegel.de\/wirtschaft\/soziales\/corona-krise-der-schmu-mit-der-kurzarbeit-a-6284e8a0-be2d-4519-b93b-a70e819d8f6f\" target=\"_blank\" rel=\"noreferrer noopener\">f\u00fcr den Arbeitgeber fast unm\u00f6glich zu kontrollieren sei, wie viel seine Besch\u00e4ftigten tats\u00e4chlich arbeiten<\/a>\u201c.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-retarus-feature-als-wichtiger-baustein-f-r-beweisf-hrung\">Retarus-Feature als wichtiger Baustein f\u00fcr Beweisf\u00fchrung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Einige Kunden der <a href=\"https:\/\/www.retarus.com\/de\/secure-email-platform\/\" target=\"_blank\" rel=\"noreferrer noopener\">Retarus Secure Email Platform<\/a> nutzen als einen Baustein f\u00fcr diese schwierige \u201eBeweisf\u00fchrung\u201c seit geraumer Zeit das Feature <a href=\"https:\/\/www.retarus.com\/de\/services\/email-security\/tech-specs\/#quiet-time\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Quiet Time<\/em><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Funktion erm\u00f6glicht es Arbeitgebern, Zeitintervalle festzulegen, in denen Mitarbeitern keine externen E-Mails zugestellt, sondern stattdessen in einer Queue in der Retarus Enterprise Cloud zwischengespeichert werden. Neben dem aktuellen Anwendungsfall, wird dieses Tool f\u00fcr gew\u00f6hnlich <a href=\"https:\/\/www.retarus.com\/blog\/de\/wir-haetten-da-was-lieber-porsche-betriebsrat\/\" target=\"_blank\" rel=\"noreferrer noopener\">bei Initiativen zur\u00a0 Work-Life-Balance<\/a> oder f\u00fcr <a href=\"https:\/\/www.retarus.com\/blog\/de\/aktuelle-sicherheitsluecken-in-ms-exchange-e-mail-continuity-fuer-den-ernstfall\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wartungsfenster beim E-Mail-Server<\/a> (z.B. Migration von Anwender-Mailboxen, Einspielen von Patches) eingesetzt. Letzteres bietet auch <a href=\"https:\/\/www.retarus.com\/de\/company\/become-a-partner\/\" target=\"_blank\" rel=\"noreferrer noopener\">Retarus Partnern<\/a> ein m\u00e4chtiges Steuerungswerkzeug f\u00fcr den E-Mail-Kommunikationskanal der Kunden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Retarus <em>Quiet Time <\/em>umfasst folgende M\u00f6glichkeiten:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Konfiguration E-Mail-freier Zeitintervalle (externe E-Mails)<\/li><li>Individuelle Einstellungen f\u00fcr unterschiedliche Anwenderprofile<\/li><li>Sichere Zwischenspeicherung der E-Mails in den Retarus-Rechenzentren<\/li><li>Automatische Zustellung der E-Mails nach Ablauf der definierten Zeitintervalle<\/li><li>Durchleitfunktion f\u00fcr E-Mails mit hoher Priorit\u00e4t<\/li><li>Notfall-Button f\u00fcr die sofortige Zustellung von E-Mails in E-Mail-freien Zeitr\u00e4umen<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden. Aktuell besonders n\u00fctzlich f\u00fcr die &#8220;Beweisf\u00fchrung&#8221; in Zusammenhang mit Kurzarbeit.<\/p>\n","protected":false},"author":12,"featured_media":15091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_s2mail":"","footnotes":""},"categories":[7,20],"tags":[159],"class_list":["post-15089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-product-news","tag-email-security"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kurzarbeit &amp; Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt - Retarus Corporate Blog - DE<\/title>\n<meta name=\"description\" content=\"Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt\" \/>\n<meta property=\"og:description\" content=\"Arbeitgeber k\u00f6nnen Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails erhalten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - DE\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-19T14:04:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-22T11:59:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00f6ren Schulte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kurzarbeit &amp; Home Office: Feature erleichtert Arbeitszeitnachweis\" \/>\n<meta name=\"twitter:description\" content=\"Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime.png\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00f6ren Schulte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/\"},\"author\":{\"name\":\"S\u00f6ren Schulte\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/da5eb37e5936738ea4e12be8b429433d\"},\"headline\":\"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt\",\"datePublished\":\"2021-03-19T14:04:42+00:00\",\"dateModified\":\"2021-03-22T11:59:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/\"},\"wordCount\":320,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/03\\\/retarus_quietime.png\",\"keywords\":[\"Email Security\"],\"articleSection\":[\"News\",\"Product News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/\",\"name\":\"Kurzarbeit & Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt - Retarus Corporate Blog - DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/03\\\/retarus_quietime.png\",\"datePublished\":\"2021-03-19T14:04:42+00:00\",\"dateModified\":\"2021-03-22T11:59:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/da5eb37e5936738ea4e12be8b429433d\"},\"description\":\"Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/03\\\/retarus_quietime.png\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/03\\\/retarus_quietime.png\",\"width\":1996,\"height\":1123,\"caption\":\"Herausforderung in vielerlei Hinsicht: Home Office in Zeiten von Corona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\",\"name\":\"Retarus Corporate Blog - DE\",\"description\":\"Immer up-to-date\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/da5eb37e5936738ea4e12be8b429433d\",\"name\":\"S\u00f6ren Schulte\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/author\\\/sschulte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kurzarbeit & Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt - Retarus Corporate Blog - DE","description":"Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/","og_locale":"de_DE","og_type":"article","og_title":"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt","og_description":"Arbeitgeber k\u00f6nnen Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails erhalten.","og_url":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/","og_site_name":"Retarus Corporate Blog - DE","article_published_time":"2021-03-19T14:04:42+00:00","article_modified_time":"2021-03-22T11:59:15+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime-1024x576.png","type":"image\/png"}],"author":"S\u00f6ren Schulte","twitter_card":"summary_large_image","twitter_title":"Kurzarbeit & Home Office: Feature erleichtert Arbeitszeitnachweis","twitter_description":"Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden.","twitter_image":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime.png","twitter_misc":{"Verfasst von":"S\u00f6ren Schulte","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/"},"author":{"name":"S\u00f6ren Schulte","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/da5eb37e5936738ea4e12be8b429433d"},"headline":"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt","datePublished":"2021-03-19T14:04:42+00:00","dateModified":"2021-03-22T11:59:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/"},"wordCount":320,"commentCount":0,"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime.png","keywords":["Email Security"],"articleSection":["News","Product News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/","url":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/","name":"Kurzarbeit & Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt - Retarus Corporate Blog - DE","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime.png","datePublished":"2021-03-19T14:04:42+00:00","dateModified":"2021-03-22T11:59:15+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/da5eb37e5936738ea4e12be8b429433d"},"description":"Mit Retarus Quiet Time k\u00f6nnen Arbeitgeber individuelle Zeitintervalle festlegen, in denen Mitarbeitern keine E-Mails zugestellt werden.","breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime.png","contentUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2021\/03\/retarus_quietime.png","width":1996,"height":1123,"caption":"Herausforderung in vielerlei Hinsicht: Home Office in Zeiten von Corona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/de\/kurzarbeit-und-home-office-wie-ein-retarus-feature-firmen-beim-arbeitszeitnachweis-unterstuetzt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Kurzarbeit und Home Office: Wie ein Retarus-Feature Firmen beim Arbeitszeitnachweis unterst\u00fctzt"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/de\/#website","url":"https:\/\/www.retarus.com\/blog\/de\/","name":"Retarus Corporate Blog - DE","description":"Immer up-to-date","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/da5eb37e5936738ea4e12be8b429433d","name":"S\u00f6ren Schulte","url":"https:\/\/www.retarus.com\/blog\/de\/author\/sschulte\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/15089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=15089"}],"version-history":[{"count":8,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/15089\/revisions"}],"predecessor-version":[{"id":15100,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/15089\/revisions\/15100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media\/15091"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=15089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=15089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=15089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}