{"id":606,"date":"2015-08-13T11:35:12","date_gmt":"2015-08-13T09:35:12","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/de\/?p=606"},"modified":"2021-08-20T09:32:09","modified_gmt":"2021-08-20T07:32:09","slug":"ab-in-die-cloud","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/","title":{"rendered":"Ab in die Cloud?"},"content":{"rendered":"<p>Die Cloud ist nicht sicher? Der Schutz sensibler Daten ist in der Wolke nicht gew\u00e4hrleistet? Die Anforderungen weltweit t\u00e4tiger Unternehmen lassen sich mithilfe von Managed Services nicht richtig umsetzen? Compliance-Richtlinien sind in der Cloud nicht realisierbar? Im Gegenteil!<\/p>\n<h3>Jedes zweite deutsche Unternehmen setzt auf E-Mail-Security aus der Cloud<\/h3>\n<div id=\"attachment_608\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\"><img aria-describedby=\"caption-attachment-608\" decoding=\"async\" class=\"wp-image-608 size-medium\" src=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\" alt=\"Planen Sie, in naher Zukunft auf E-Mail-Security-Services umzustellen?\" width=\"300\" height=\"169\" \/><\/a><p id=\"caption-attachment-608\" class=\"wp-caption-text\">Planen Sie, in naher Zukunft auf E-Mail-Security-Services umzustellen?<\/p><\/div>\n<p>Dass immer mehr Unternehmen<a href=\"https:\/\/www.retarus.com\/blog\/de\/trotz-sicherheitsbedenken-unternehmen-setzen-auf-cloud-services\/\" target=\"_blank\" rel=\"noopener noreferrer\"> trotz Sicherheitsbedenken auf Cloud-basierende L\u00f6sungen setzen<\/a>, ist nichts Neues. Dass Cloud Services jedoch immer h\u00e4ufiger dazu genutzt werden, um die gesch\u00e4ftliche E-Mail-Kommunikation gezielt vor dem Fremdzugriff Dritter abzusichern, allerdings schon. Schlie\u00dflich geht es hier um den Austausch sensibler Informationen wie beispielsweise gesch\u00e4ftskritische Zahlen oder personenbezogene Daten. Dies belegt auch eine aktuelle Studie, die Retarus in Zusammenarbeit mit dem Marktforschungsinstitut <a href=\"http:\/\/www.researchinaction.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Research in Action<\/a> erstellt hat: Demnach planen in Deutschland etwa 49 Prozent der Befragten die Umstellung auf E-Mail-Security-Services. In Frankreich m\u00f6chten immerhin circa 46 Prozent ihre E-Mail-Kommunikation in die Cloud verlagern, in Gro\u00dfbritannien sind es sogar 62 Prozent. Am st\u00e4rksten ist die Nachfrage nach E-Mail Security dabei in Tourismus und Logistik: Rund 70 Prozent der Befragten aus diesen Bereichen gaben an, zeitnah auf Cloud-Dienste umstellen zu wollen. Die Studie basiert auf Angaben von Entscheidern aus 900 Unternehmen aller Gr\u00f6\u00dfen und Branchen.<\/p>\n<div id=\"attachment_607\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_by-branches.jpg\"><img aria-describedby=\"caption-attachment-607\" decoding=\"async\" class=\"wp-image-607 size-medium\" src=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_by-branches.jpg\" alt=\"Planen Sie, in naher Zukunft auf E-Mail-Security-Services umzustellen?\" width=\"300\" height=\"169\" \/><\/a><p id=\"caption-attachment-607\" class=\"wp-caption-text\">Planen Sie, in naher Zukunft auf E-Mail-Security-Services umzustellen?<\/p><\/div>\n<h3>Sichere und flexible E-Mail-Kommunikation<\/h3>\n<p>Neben der <a href=\"https:\/\/www.zeit.de\/digital\/datenschutz\/2013-10\/hintergrund-nsa-skandal\" target=\"_blank\" rel=\"noopener noreferrer\">NSA-Aff\u00e4re<\/a> haben vor allem die zunehmend raffinierteren Cyberangriffsmethoden sowie immer strengere gesetzliche Vorgaben und Compliance-Richtlinien die Aufmerksamkeit der IT-Entscheider in Richtung Managed Services gelenkt. Alle aktuellen Anforderungen mit selbstbetriebenen Systemen zu erf\u00fcllen, w\u00e4re sehr aufw\u00e4ndig.<\/p>\n<p><a href=\"https:\/\/www.retarus.com\/de\/products\/retarus-email-security\/\" target=\"_blank\" rel=\"noopener noreferrer\">Managed E-Mail Services<\/a> hingegen bieten viele Vorteile: Sie sind einfach implementierbar und bieten umfassenden Virenschutz sowie Spam- und Phishing-Filter. Im Unterschied zu On-Premise-Systemen sind Cloud-Dienste jederzeit beliebig skalierbar. Aufwand und Kosten richten sich folglich stets nach dem aktuellen Bedarf. E-Mail-Server und Backup-Infrastruktur werden sp\u00fcrbar entlastet, die Performance steigert sich deutlich. Zudem lassen sich Compliance-Richtlinien oder Branchenstandards sowie landesspezifische oder internationale gesetzliche Vorgaben, wie etwa HIPAA oder die EU Data Protection Directive, mithilfe von Managed Services einfach umsetzen. Mittels SLAs k\u00f6nnen sich die Kunden verbindlich zusichern lassen, wo und nach welchen gesetzlichen Regelungen die Datenverarbeitung genau erfolgt. Durch den Einsatz von Managed Services profitieren Unternehmen folglich von optimierten Gesch\u00e4ftsprozessen \u2013 und k\u00f6nnen ihre Ressourcen wieder auf Kernkompetenzen fokussieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Cloud ist nicht sicher? Der Schutz sensibler Daten ist in der Wolke nicht gew\u00e4hrleistet? Die Anforderungen weltweit t\u00e4tiger Unternehmen lassen sich mithilfe von Managed Services nicht richtig umsetzen? Compliance-Richtlinien sind in der Cloud nicht realisierbar? Im Gegenteil! Eine Studie belegt: In Deutschland planen ca. 49 Prozent der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich rund 46 Prozent, in Gro\u00dfbritannien 62 Prozent. <\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_s2mail":"","footnotes":""},"categories":[51,13],"tags":[159,130,131],"class_list":["post-606","post","type-post","status-publish","format-standard","hentry","category-business-trends","category-cloud","tag-email-security","tag-research-in-action","tag-retarus-studie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ab in die Cloud<\/title>\n<meta name=\"description\" content=\"Studie belegt: In Deutschland planen ca. 49 % der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich 46 %, in UK 62 %.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ab in die Cloud?\" \/>\n<meta property=\"og:description\" content=\"Studie belegt: In Deutschland planen ca. 49 % der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich 46 %, in UK 62 %.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - DE\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-13T09:35:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-20T07:32:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\" \/>\n<meta name=\"author\" content=\"Sabrina Hiller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabrina Hiller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/\"},\"author\":{\"name\":\"Sabrina Hiller\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/b52ddf77ed41a8431c9b47c4d18942d7\"},\"headline\":\"Ab in die Cloud?\",\"datePublished\":\"2015-08-13T09:35:12+00:00\",\"dateModified\":\"2021-08-20T07:32:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/\"},\"wordCount\":397,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/08\\\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\",\"keywords\":[\"Email Security\",\"Research in Action\",\"Retarus Studie\"],\"articleSection\":[\"Business Trends\",\"Cloud\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/\",\"name\":\"Ab in die Cloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/08\\\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\",\"datePublished\":\"2015-08-13T09:35:12+00:00\",\"dateModified\":\"2021-08-20T07:32:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/b52ddf77ed41a8431c9b47c4d18942d7\"},\"description\":\"Studie belegt: In Deutschland planen ca. 49 % der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich 46 %, in UK 62 %.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/08\\\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2015\\\/08\\\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg\",\"width\":2833,\"height\":1600,\"caption\":\"In Deutschland planen ca. 49 Prozent der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich rund 46 Prozent, in Gro\u00dfbritannien 62 Prozent.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/ab-in-die-cloud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ab in die Cloud?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/\",\"name\":\"Retarus Corporate Blog - DE\",\"description\":\"Immer up-to-date\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/b52ddf77ed41a8431c9b47c4d18942d7\",\"name\":\"Sabrina Hiller\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/de\\\/author\\\/shiller\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ab in die Cloud","description":"Studie belegt: In Deutschland planen ca. 49 % der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich 46 %, in UK 62 %.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/","og_locale":"de_DE","og_type":"article","og_title":"Ab in die Cloud?","og_description":"Studie belegt: In Deutschland planen ca. 49 % der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich 46 %, in UK 62 %.","og_url":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/","og_site_name":"Retarus Corporate Blog - DE","article_published_time":"2015-08-13T09:35:12+00:00","article_modified_time":"2021-08-20T07:32:09+00:00","og_image":[{"url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg","type":"","width":"","height":""}],"author":"Sabrina Hiller","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sabrina Hiller","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/"},"author":{"name":"Sabrina Hiller","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/b52ddf77ed41a8431c9b47c4d18942d7"},"headline":"Ab in die Cloud?","datePublished":"2015-08-13T09:35:12+00:00","dateModified":"2021-08-20T07:32:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/"},"wordCount":397,"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg","keywords":["Email Security","Research in Action","Retarus Studie"],"articleSection":["Business Trends","Cloud"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/","url":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/","name":"Ab in die Cloud","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg","datePublished":"2015-08-13T09:35:12+00:00","dateModified":"2021-08-20T07:32:09+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/b52ddf77ed41a8431c9b47c4d18942d7"},"description":"Studie belegt: In Deutschland planen ca. 49 % der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich 46 %, in UK 62 %.","breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg","contentUrl":"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2015\/08\/Retarus_Research-in-Action-Studie_E-Mail_Sec_by-regions.jpg","width":2833,"height":1600,"caption":"In Deutschland planen ca. 49 Prozent der Befragten die Umstellung auf E-Mail-Security-Services, in Frankreich rund 46 Prozent, in Gro\u00dfbritannien 62 Prozent."},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/de\/ab-in-die-cloud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Ab in die Cloud?"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/de\/#website","url":"https:\/\/www.retarus.com\/blog\/de\/","name":"Retarus Corporate Blog - DE","description":"Immer up-to-date","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/de\/#\/schema\/person\/b52ddf77ed41a8431c9b47c4d18942d7","name":"Sabrina Hiller","url":"https:\/\/www.retarus.com\/blog\/de\/author\/shiller\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=606"}],"version-history":[{"count":6,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/606\/revisions"}],"predecessor-version":[{"id":14806,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/606\/revisions\/14806"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}