{"id":7912,"date":"2024-04-04T17:14:05","date_gmt":"2024-04-04T15:14:05","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca"},"modified":"2024-05-07T19:58:29","modified_gmt":"2024-05-07T17:58:29","slug":"desmantelamiento-global-de-la-rtc-el-final-esta-cerca","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/","title":{"rendered":"Desmantelamiento global de la RTC: el final est\u00e1 cerca"},"content":{"rendered":" <p class=\"wp-block-paragraph\">Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). S\u00f3lo un apunte: la desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa. Es importante que las empresas sean proactivas y sustituyan lo anal\u00f3gico por lo digital cuanto antes.<\/p>   <p class=\"wp-block-paragraph\">Si bien algunos pa\u00edses todav\u00eda no han establecido los plazos para el cambio, en <strong>Espa\u00f1a<\/strong>, la empresa Telef\u00f3nica y <a href=\"https:\/\/www.telefonica.com\/es\/sala-comunicacion\/prensa\/telefonica-cierra-todas-sus-centrales-de-cobre-y-pone-rumbo-a-su-centenario\/\" target=\"_blank\" rel=\"noreferrer noopener\">su proyecto FARO<\/a> han fijado ya un rumbo diferente. En un principio, Telef\u00f3nica hab\u00eda planificado dejar de utilizar sus redes de cobre el 19 de abril de 2024, la fecha de su centenario. Finalmente, el proyecto se alargar\u00e1 hasta marzo de 2026, aunque la mayor\u00eda de las centrales que todav\u00eda siguen activas se cerrar\u00e1n antes de finales de este a\u00f1o. Para las empresas espa\u00f1olas, el cierre de 8.532 centrales implica que las l\u00edneas de cobre dejar\u00e1n de estar operativas y que toda la comunicaci\u00f3n de voz deber\u00e1 migrarse a IP. Es posible que se pase por alto una consecuencia imprevista: la comunicaci\u00f3n por fax.<\/p>   <p class=\"wp-block-paragraph\">En Espa\u00f1a, las l\u00edneas anal\u00f3gicas todav\u00eda se utilizan masivamente para la comunicaci\u00f3n por fax del gobierno o en empresas del sector financiero, industrial o de otros mercados. Dado que Telef\u00f3nica gestiona toda la red espa\u00f1ola de cobre, el cierre de las centrales significa que las empresas ya no podr\u00e1n enviar ni recibir faxes, independientemente del proveedor de telefon\u00eda que utilicen. Esto significa que ha llegado el momento de la verdad, y que las organizaciones necesitan planificar e implementar nuevas soluciones \u2013basadas en la nube\u2013 capaces de ofrecer <a href=\"https:\/\/www.retarus.com\/es\/services\/fax\/\">fax sobre IP<\/a>.<\/p>   <h2 class=\"wp-block-heading\" id=\"h-other-key-timelines-across-the-globe\">Otras fechas clave en el mundo<\/h2>   <p class=\"wp-block-paragraph\">No existe una fecha \u00fanica ni ning\u00fan mandato global, por lo que el desmantelamiento de la tecnolog\u00eda heredada es un proceso que los operadores y proveedores de telecomunicaciones vienen arrastrando hace tiempo. Los pa\u00edses, y m\u00e1s espec\u00edficamente las empresas, han optado por definir sus propios plazos.<\/p>   <p class=\"wp-block-paragraph\">Sin embargo, no todos los pa\u00edses, ni todos los operadores, van a desmantelar por completo la RTC. En algunos pa\u00edses, las l\u00edneas anal\u00f3gicas podr\u00e1n seguir siendo utilizadas por los clientes existentes, pero la tarificaci\u00f3n de esta tecnolog\u00eda suele haberse liberalizado. B\u00e1sicamente, esto significa que el precio de instalaci\u00f3n, uso y mantenimiento ser\u00e1 cada vez m\u00e1s caro.<\/p>   <p class=\"wp-block-paragraph\">En los <strong>EE.UU.<\/strong>, la FCC emiti\u00f3 un mandato federal relativo al desmantelamiento de la RTC a finales de 2022, por el que los proveedores estaban obligados a reemplazar las l\u00edneas \u00abPOTS\u00bb (Plain Old Telephone Service) por un servicio alternativo, con una soluci\u00f3n digital. Esto ha hecho que muchos proveedores y empresas de telecomunicaciones hayan suspendido sus funciones de mantenimiento y soporte para dichos servicios.<\/p>   <p class=\"wp-block-paragraph\">En <strong>Francia<\/strong>, Orange, de manera similar al proceso que ha tenido lugar en Espa\u00f1a, ha anunciado el final de las l\u00edneas telef\u00f3nicas fijas y ha dejado de ofrecer nuevas suscripciones para este servicio. Hasta 2030 estar\u00e1n transfiriendo a digital todas las l\u00edneas anal\u00f3gicas del pa\u00eds.<\/p>   <p class=\"wp-block-paragraph\">En <strong>Reino Unido<\/strong> se prev\u00e9 que la desaparici\u00f3n de las l\u00edneas \u00abPOTS\u00bb se haya completado para diciembre de 2025. Para esa fecha, las redes telef\u00f3nicas p\u00fablicas conmutadas (RTPC) y la infraestructura asociada a ellas dejar\u00e1n de estar totalmente operativas.<\/p>   <p class=\"wp-block-paragraph\">En el caso de <strong>Canad\u00e1<\/strong>, la mayor\u00eda de los proveedores de telecomunicaciones ya no instalan nuevas l\u00edneas telef\u00f3nicas de cobre. El proceso empez\u00f3 en el a\u00f1o 2023 y, desde entonces, pr\u00e1cticamente todos han retirado sus redes de cobre. Adem\u00e1s, han dejado de ofrecer Internet DSL puesto que este servicio se proporciona a trav\u00e9s de l\u00edneas de cobre. Asimismo, los operadores de Tier-1 est\u00e1n indicando a sus clientes en Am\u00e9rica del Norte \u2013y en todo el mundo\u2013 que dejen de utilizar el servicio de acceso a Internet TDM (T1, T3\/45, etc.) y las l\u00edneas \u00abPOTS\u00bb. Los principales agentes del sector como Bell Canada y TELUS International han cesado oficialmente el uso del cobre.<\/p>   <p class=\"wp-block-paragraph\">En <strong>Australia y Nueva Zelanda<\/strong>, el servicio telef\u00f3nico fijo se interrumpir\u00e1 18 meses despu\u00e9s del despliegue de la banda ancha. A pesar del anuncio de la eliminaci\u00f3n, los plazos y la fecha final espec\u00edfica no quedan claros.<\/p>   <p class=\"wp-block-paragraph\">\u00bfNo ha visto una menci\u00f3n a cierto pa\u00eds? Retarus mantiene relaciones con multitud \u2013y muy diversos\u2013 operadores y organismos regulatorios de todo el mundo. Si desea obtener detalles espec\u00edficos sobre alg\u00fan pa\u00eds espec\u00edfico o sobre las tendencias relacionadas con IP, <a href=\"https:\/\/www.retarus.com\/es\/contact\/\">d\u00edganoslo.<\/a> Estaremos encantados de orientarle sobre la legislaci\u00f3n vigente y sobre el impacto que supone para sus comunicaciones comerciales.<\/p> ","protected":false},"excerpt":{"rendered":"<p>Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.<\/p>\n","protected":false},"author":44,"featured_media":7913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[3819],"class_list":["post-7912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cloud-fax"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Desmantelamiento global de la RTC: el final est\u00e1 cerca - Retarus Corporate Blog - ES<\/title>\n<meta name=\"description\" content=\"Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desmantelamiento global de la RTC: el final est\u00e1 cerca\" \/>\n<meta property=\"og:description\" content=\"Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - ES\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T15:14:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T17:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/es\/wp-content\/uploads\/sites\/26\/2024\/04\/AdobeStock_141611205.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"James Pepe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Pepe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/\"},\"author\":{\"name\":\"James Pepe\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/9af8fdc422a956541cde96175efb498e\"},\"headline\":\"Desmantelamiento global de la RTC: el final est\u00e1 cerca\",\"datePublished\":\"2024-04-04T15:14:05+00:00\",\"dateModified\":\"2024-05-07T17:58:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/\"},\"wordCount\":844,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/04\\\/AdobeStock_141611205.jpg\",\"keywords\":[\"Cloud Fax\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/\",\"name\":\"Desmantelamiento global de la RTC: el final est\u00e1 cerca - Retarus Corporate Blog - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/04\\\/AdobeStock_141611205.jpg\",\"datePublished\":\"2024-04-04T15:14:05+00:00\",\"dateModified\":\"2024-05-07T17:58:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/9af8fdc422a956541cde96175efb498e\"},\"description\":\"Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/04\\\/AdobeStock_141611205.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2024\\\/04\\\/AdobeStock_141611205.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desmantelamiento global de la RTC: el final est\u00e1 cerca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/\",\"name\":\"Retarus Corporate Blog - ES\",\"description\":\"Siempre al d\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/9af8fdc422a956541cde96175efb498e\",\"name\":\"James Pepe\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/es\\\/author\\\/jamesp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Desmantelamiento global de la RTC: el final est\u00e1 cerca - Retarus Corporate Blog - ES","description":"Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/","og_locale":"es_ES","og_type":"article","og_title":"Desmantelamiento global de la RTC: el final est\u00e1 cerca","og_description":"Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.","og_url":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/","og_site_name":"Retarus Corporate Blog - ES","article_published_time":"2024-04-04T15:14:05+00:00","article_modified_time":"2024-05-07T17:58:29+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.retarus.com\/blog\/es\/wp-content\/uploads\/sites\/26\/2024\/04\/AdobeStock_141611205.jpg","type":"image\/jpeg"}],"author":"James Pepe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"James Pepe","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/"},"author":{"name":"James Pepe","@id":"https:\/\/www.retarus.com\/blog\/es\/#\/schema\/person\/9af8fdc422a956541cde96175efb498e"},"headline":"Desmantelamiento global de la RTC: el final est\u00e1 cerca","datePublished":"2024-04-04T15:14:05+00:00","dateModified":"2024-05-07T17:58:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/"},"wordCount":844,"commentCount":0,"image":{"@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/es\/wp-content\/uploads\/sites\/26\/2024\/04\/AdobeStock_141611205.jpg","keywords":["Cloud Fax"],"articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/","url":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/","name":"Desmantelamiento global de la RTC: el final est\u00e1 cerca - Retarus Corporate Blog - ES","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/es\/wp-content\/uploads\/sites\/26\/2024\/04\/AdobeStock_141611205.jpg","datePublished":"2024-04-04T15:14:05+00:00","dateModified":"2024-05-07T17:58:29+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/es\/#\/schema\/person\/9af8fdc422a956541cde96175efb498e"},"description":"Los plazos para el desmantelamiento de la Red Telef\u00f3nica Conmutada (RTC) en EE.UU. y Europa est\u00e1n cada vez m\u00e1s cerca, por lo que es urgente que las empresas migren sus comunicaciones de voz a IP (dado que todas las centrales telef\u00f3nicas dejar\u00e1n de estar operativas en breve). La desconexi\u00f3n afecta tanto a EE.UU. como a todos los pa\u00edses de Europa.","breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/es\/wp-content\/uploads\/sites\/26\/2024\/04\/AdobeStock_141611205.jpg","contentUrl":"https:\/\/www.retarus.com\/blog\/es\/wp-content\/uploads\/sites\/26\/2024\/04\/AdobeStock_141611205.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/es\/desmantelamiento-global-de-la-rtc-el-final-esta-cerca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"Desmantelamiento global de la RTC: el final est\u00e1 cerca"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/es\/#website","url":"https:\/\/www.retarus.com\/blog\/es\/","name":"Retarus Corporate Blog - ES","description":"Siempre al d\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/es\/#\/schema\/person\/9af8fdc422a956541cde96175efb498e","name":"James Pepe","url":"https:\/\/www.retarus.com\/blog\/es\/author\/jamesp\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/posts\/7912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=7912"}],"version-history":[{"count":2,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/posts\/7912\/revisions"}],"predecessor-version":[{"id":9290,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/posts\/7912\/revisions\/9290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/media\/7913"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=7912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=7912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=7912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}