{"id":2157,"date":"2017-05-12T14:54:06","date_gmt":"2017-05-12T12:54:06","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-offre-de-nouvelles-fonctions-pour-une-protection-renforcee-contre-les-spams"},"modified":"2024-05-07T19:38:38","modified_gmt":"2024-05-07T17:38:38","slug":"retarus-antispam-or-less-is-sometimes-actually-more","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/","title":{"rendered":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams"},"content":{"rendered":" <h2 class=\"wp-block-heading\" id=\"h-effektiver-spam-schutz-dank-retarus-antispam-management\">Une protection efficace contre les spams gr\u00e2ce \u00e0 Retarus AntiSpam Management<\/h2>  <p>Les clients de Retarus Email Security b\u00e9n\u00e9ficient d\u00e9sormais d&rsquo;une nouvelle fonction de liste noire dynamique pour une protection antispam am\u00e9lior\u00e9e.<\/p> <p>Lorsque de nombreux e-mails suspects envoy\u00e9s \u00e0 des destinataires inconnus depuis une adresse IP entrent dans l&rsquo;infrastructure Retarus, ces messages sont d&rsquo;abord r\u00e9ceptionn\u00e9s plus lentement avant d&rsquo;\u00eatre trait\u00e9s (\u00ab&nbsp;tarpit&nbsp;\u00bb). En cas de charge \u00e9lev\u00e9e continue, les connexions sont alors interrompues et l&rsquo;adresse IP \u00e0 l&rsquo;origine des envois est inscrite sur une liste noire provisoire.<\/p> <p><a href=\"https:\/\/www.retarus.com\/fr\/services\/email-security\/tech-specs\/#directory-filter\">Le Directory Filter<\/a> est techniquement en charge de cette t\u00e2che car il est toujours en capacit\u00e9 de r\u00e9guler le trafic. Il dispose d\u00e9sormais d&rsquo;une nouvelle fonction qui nous permet de l&rsquo;alimenter en informations, afin de d\u00e9tecter les spams avec une probabilit\u00e9 de 100&nbsp;%.<\/p> <p>Le volume de spams renvoy\u00e9s vers le Directory Filter \u00e9tant maintenant plus important, cela contribue \u00e0 r\u00e9duire le volume de spams atteignant le <a href=\"https:\/\/www.retarus.com\/fr\/services\/email-security\/tech-specs\/#antispam\">filtre antispam d\u00e9di\u00e9<\/a> et envoy\u00e9s par la suite en quarantaine. Pour notre client, il n&rsquo;y a toutefois aucune raison d&rsquo;\u00eatre inquiet&nbsp;: Si le nombre de messages marqu\u00e9s comme spams pr\u00e9sents en quarantaine est moins \u00e9lev\u00e9, cela d\u00e9coule uniquement du fait que bien plus de spams provenant d&rsquo;adresses IP clairement douteuses ont d\u00e9j\u00e0 \u00e9chou\u00e9 en amont au niveau du Directory Filter et n&rsquo;ont m\u00eame pas pu arriver jusqu&rsquo;\u00e0 l&rsquo;analyse via AntiSpam. Le rapport Email Security est d\u00e9sormais plus clair (gr\u00e2ce \u00e0 moins d&rsquo;entr\u00e9es) et les e-mails importants sont achemin\u00e9s plus rapidement. Nous nous r\u00e9jouissons du fait <a href=\"https:\/\/www.retarus.com\/blog\/fr\/spam-wave-online-fraudsters-bank-on-stock-market-manipulation\/\">qu&rsquo;en cette p\u00e9riode d&rsquo;apparition massive de spams<\/a>, nos syst\u00e8mes enregistrent un volume trois \u00e0 quatre fois plus \u00e9lev\u00e9 qu&rsquo;en d\u00e9but d&rsquo;ann\u00e9e.<\/p> <p><a href=\"https:\/\/www.retarus.com\/blog\/de\/retarus-antispam-oder-weniger-ist-manchmal-mehr\/e-mail_security_overview_new_1280px\/\" rel=\"attachment wp-att-10912\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10912\" src=\"https:\/\/www.retarus.com\/blog\/de\/wp-content\/uploads\/sites\/4\/2017\/05\/e-mail_security_overview_new_1280px.png\" alt=\"Ablaufgrafik Retarus E-Mail Security, Stand Mai 2017\" width=\"1280\" height=\"1484\"><\/a><\/p> <p><a href=\"https:\/\/www.retarus.com\/fr\/services\/email-security\/\">Retarus Email Security<\/a> est une solution compl\u00e8te pour une communication par e-mail exempte de virus et de spams int\u00e9grant une large gamme de fonctions, dont notre <a href=\"https:\/\/www.retarus.com\/fr\/services\/email-security\/#patient-zero-detection\">nouveau Patient Zero Detection<sup>\u00ae<\/sup><\/a>, qui d\u00e9tecte par la suite les messages infect\u00e9s dans la bo\u00eete de r\u00e9ception afin de pouvoir prot\u00e9ger votre entreprise contre les co\u00fbts \u00e9lev\u00e9s occasionn\u00e9s. Pour en savoir plus, cliquez <a href=\"https:\/\/www.retarus.com\/fr\/services\/email-security\/\">ici<\/a> ou contactez directement votre <a href=\"https:\/\/www.retarus.com\/fr\/contact\/\">interlocuteur Retarus sur place<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l&rsquo;aide d&rsquo;une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.<\/p>\n","protected":false},"author":14,"featured_media":2158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[9,15],"tags":[102,26],"class_list":["post-2157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product-news","category-security","tag-email-security","tag-spam"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams<\/title>\n<meta name=\"description\" content=\"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l&#039;aide d&#039;une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams\" \/>\n<meta property=\"og:description\" content=\"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l&#039;aide d&#039;une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - FR\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-12T12:54:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T17:38:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2017\/05\/spam-spam-spam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Cloer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams\" \/>\n<meta name=\"twitter:description\" content=\"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l&#039;aide d&#039;une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Cloer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/\"},\"author\":{\"name\":\"Thomas Cloer\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"headline\":\"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams\",\"datePublished\":\"2017-05-12T12:54:06+00:00\",\"dateModified\":\"2024-05-07T17:38:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/\"},\"wordCount\":407,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2017\\\/05\\\/spam-spam-spam.jpg\",\"keywords\":[\"Email Security\",\"Spam\"],\"articleSection\":[\"Product News\",\"Security\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/\",\"name\":\"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2017\\\/05\\\/spam-spam-spam.jpg\",\"datePublished\":\"2017-05-12T12:54:06+00:00\",\"dateModified\":\"2024-05-07T17:38:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\"},\"description\":\"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l'aide d'une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2017\\\/05\\\/spam-spam-spam.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2017\\\/05\\\/spam-spam-spam.jpg\",\"width\":730,\"height\":410,\"caption\":\"Spam; Foto: Luca Conti via flickr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/retarus-antispam-or-less-is-sometimes-actually-more\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/\",\"name\":\"Retarus Corporate Blog - FR\",\"description\":\"Restez inform\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/7f8954d8bf84d75cf384942c5f6cf2e5\",\"name\":\"Thomas Cloer\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/author\\\/thomasc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams","description":"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l'aide d'une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/","og_locale":"fr_FR","og_type":"article","og_title":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams","og_description":"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l'aide d'une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.","og_url":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/","og_site_name":"Retarus Corporate Blog - FR","article_published_time":"2017-05-12T12:54:06+00:00","article_modified_time":"2024-05-07T17:38:38+00:00","og_image":[{"width":730,"height":410,"url":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2017\/05\/spam-spam-spam.jpg","type":"image\/jpeg"}],"author":"Thomas Cloer","twitter_card":"summary_large_image","twitter_title":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams","twitter_description":"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l'aide d'une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.","twitter_misc":{"\u00c9crit par":"Thomas Cloer","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/"},"author":{"name":"Thomas Cloer","@id":"https:\/\/www.retarus.com\/blog\/fr\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"headline":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams","datePublished":"2017-05-12T12:54:06+00:00","dateModified":"2024-05-07T17:38:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/"},"wordCount":407,"image":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2017\/05\/spam-spam-spam.jpg","keywords":["Email Security","Spam"],"articleSection":["Product News","Security"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/","url":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/","name":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2017\/05\/spam-spam-spam.jpg","datePublished":"2017-05-12T12:54:06+00:00","dateModified":"2024-05-07T17:38:38+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5"},"description":"Retarus Email Security offre d\u00e9sormais une protection am\u00e9lior\u00e9e contre les spams \u00e0 l'aide d'une nouvelle fonction de liste noire dynamique. D\u00e9couvrez-en davantage sur le nouveau filtre antispam et sur une communication par e-mail exempte de virus et de spams gr\u00e2ce \u00e0 Retarus AntiSpam Management.","breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2017\/05\/spam-spam-spam.jpg","contentUrl":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2017\/05\/spam-spam-spam.jpg","width":730,"height":410,"caption":"Spam; Foto: Luca Conti via flickr"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/fr\/retarus-antispam-or-less-is-sometimes-actually-more\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Retarus AntiSpam offre de nouvelles fonctions pour une protection renforc\u00e9e contre les spams"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/fr\/#website","url":"https:\/\/www.retarus.com\/blog\/fr\/","name":"Retarus Corporate Blog - FR","description":"Restez inform\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/fr\/#\/schema\/person\/7f8954d8bf84d75cf384942c5f6cf2e5","name":"Thomas Cloer","url":"https:\/\/www.retarus.com\/blog\/fr\/author\/thomasc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=2157"}],"version-history":[{"count":7,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2157\/revisions"}],"predecessor-version":[{"id":8757,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2157\/revisions\/8757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/media\/2158"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=2157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=2157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=2157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}