{"id":7503,"date":"2023-09-14T14:42:02","date_gmt":"2023-09-14T12:42:02","guid":{"rendered":"https:\/\/www.retarus.com\/blog\/fr\/service-wow%c2%a0-envoi-automatise-de-grands-volumes-de-mails-depuis-servicenow"},"modified":"2024-05-07T19:46:43","modified_gmt":"2024-05-07T17:46:43","slug":"service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow","status":"publish","type":"post","link":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/","title":{"rendered":"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&rsquo;e-mails depuis ServiceNow"},"content":{"rendered":" <p>De nombreuses entreprises externalisent l&rsquo;int\u00e9gralit\u00e9 de l&rsquo;exploitation de ServiceNow aupr\u00e8s d&rsquo;int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s&rsquo;av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d&rsquo;envoi\u2026<\/p>   <p>ServiceNow \u00e9value le march\u00e9 adressable total (TAM en anglais) correspondant \u00e0 ses flux de travail informatiques, d&#8217;employ\u00e9s, de clients et de cr\u00e9ateurs \u00e0 pr\u00e8s de 190&nbsp;milliards de dollars. Actuellement, environ 85&nbsp;% des entreprises figurant au classement \u00ab\u00a0Fortune 500\u00a0\u00bb utilisent le logiciel. Pratiquement tous les acteurs majeurs du march\u00e9 de l&rsquo;informatique ont un lien avec ServiceNow, que ce soit en tant que partenaires commerciaux ou en tant que fournisseurs dont les services sont install\u00e9s via la plateforme, voire en tant qu&rsquo;int\u00e9grateurs syst\u00e8mes&nbsp;: en raison de la complexit\u00e9 de la plateforme, hautement configurable et exploit\u00e9e au sein de d\u00e9partements tels que les ressources humaines, le service client\u00e8le et l&rsquo;informatique, il arrive souvent que l&rsquo;exploitation de ServiceNow dans son ensemble soit confi\u00e9e \u00e0 des fournisseurs de services externes, et non uniquement son impl\u00e9mentation.<\/p>   <h2 class=\"wp-block-heading\" id=\"h-retarus-nbsp-le-lien-manquant-de-servicenow\">Retarus&nbsp;: le lien manquant de ServiceNow<\/h2>   <p>Jusqu&rsquo;ici, vous suivez. Mais \u00e0 quel niveau Retarus intervient-il&nbsp;? D&rsquo;une part, nos services de s\u00e9curit\u00e9 de messagerie, de SMS et de fax peuvent \u00eatre g\u00e9r\u00e9s directement via ServiceNow. Nos services sont toutefois beaucoup plus int\u00e9ressants pour nos partenaires qui int\u00e8grent et exploitent ServiceNow afin d&rsquo;aboutir \u00e0 une solution de messagerie fiable et \u00e9volutive pour l&rsquo;int\u00e9gralit\u00e9 du flux d&rsquo;applications de ServiceNow.<\/p>   <p>Il s&rsquo;agit d&rsquo;un point d&rsquo;une importance capitale, comme l&rsquo;illustre l&rsquo;exemple d&rsquo;une grande entreprise cliente multinationale&nbsp;:&nbsp; un environnement syst\u00e8me hybride comptant plus de 1&nbsp;000&nbsp;applications (sur site et SaaS, dont plusieurs instances de ServiceNow), de m\u00eame que plus de 200&nbsp;domaines via lesquels plus de 10&nbsp;millions d&rsquo;e-mails sont envoy\u00e9s chaque mois. ServiceNow g\u00e9n\u00e8re \u00e0 lui seul chez ce client environ 80&nbsp;% du flux de messagerie interne. De tels volumes d&rsquo;e-mails posent rapidement probl\u00e8me, d&rsquo;autant plus que de plus en plus d&rsquo;utilisateurs choisissent de d\u00e9manteler eux-m\u00eames leur infrastructure de messagerie et de la stocker dans le cloud, par exemple <a href=\"https:\/\/www.retarus.com\/blog\/fr\/microsoft-365-surmonter-les-defis-de-la-messagerie-pour-les-infrastructures-complexes-et-hybrides\/\">dans le cadre d&rsquo;une migration vers Microsoft 365<\/a>.<\/p>   <h2 class=\"wp-block-heading\" id=\"h-meilleures-pratiques-pour-integrateurs-systemes-et-msp\">Meilleures pratiques pour int\u00e9grateurs syst\u00e8mes et MSP<\/h2>   <p>Dans le cadre de projets, <a href=\"https:\/\/www.retarus.com\/fr\/company\/become-a-partner\/\">nos partenaires<\/a> et nous-m\u00eames nous trouvons r\u00e9guli\u00e8rement face \u00e0 la m\u00eame probl\u00e9matique&nbsp;: le client migre vers Microsoft 365 et constate t\u00f4t ou tard que l&rsquo;envoi de grands volumes d&rsquo;e-mails depuis ServiceNow via ses propres domaines entra\u00eene des interruptions de service au niveau de la gestion des services informatiques ou des processus de ressources humaines en raison des <a href=\"https:\/\/learn.microsoft.com\/fr-fr\/office365\/servicedescriptions\/exchange-online-service-description\/exchange-online-limits#sending-limits\" target=\"_blank\" rel=\"noopener\">limites d&rsquo;envoi de Microsoft<\/a>.&nbsp;Certes, ServiceNow offre ici la possibilit\u00e9 de proc\u00e9der \u00e0 l&rsquo;envoi via un sous-domaine de son syst\u00e8me. Mais de nombreux utilisateurs pr\u00e9f\u00e8rent dans ce cas utiliser leur propre domaine, pour des raisons vari\u00e9es (marque, CI\/CD, r\u00e9putation, suivi).&nbsp;Dans ce cas, il est recommand\u00e9 de recourir \u00e0 un prestataire de services appropri\u00e9 pour l&rsquo;envoi de grands volumes d&rsquo;e-mails. Lors de ce choix, plusieurs facteurs doivent \u00eatre pris en compte.<\/p>   <h2 class=\"wp-block-heading\" id=\"h-un-pour-tous-et-tous-pour-un\">Un pour tous et tous pour un<\/h2>   <p>De nombreux sp\u00e9cialistes en messagerie transactionnelle s&rsquo;attachent invariablement aux m\u00eames sc\u00e9narios d&rsquo;application comme la communication client (marketing, boutiques en ligne, etc.) et proposent ainsi uniquement des solutions pour flux sortants tr\u00e8s volumineux, sans pour autant s&rsquo;adapter au flux entrant, lequel s&rsquo;av\u00e8re pourtant tout aussi essentiel pour ServiceNow. Il manque le plus souvent \u00e0 de telles solutions des fonctions avanc\u00e9es telles que la r\u00e9\u00e9criture des adresses (Address Rewriting), le routage IP dynamique ou des t\u00e2ches multidestinataires. Aussi, pour les processus sensibles notamment dans la sph\u00e8re priv\u00e9e, le chiffrement et le respect des directives de protection des donn\u00e9es et de conformit\u00e9 sont des points importants lors du choix d&rsquo;un prestataire de services appropri\u00e9.<\/p>   <h2 class=\"wp-block-heading\" id=\"h-une-solution-complete-pour-la-messagerie-en-tant-que-principal-canal-commercial\">Une solution compl\u00e8te pour la messagerie en tant que principal canal commercial<\/h2>   <p>Chez Retarus, nous consid\u00e9rons la messagerie \u00e9lectronique dans son ensemble. Nous proposons des services de messagerie cloud professionnelle tout-en-un. <a href=\"https:\/\/www.retarus.com\/fr\/services\/email-infrastructure\/transactional-email\/\">Retarus Transactional Email<\/a> vous permet d&rsquo;envoyer de grands volumes d&rsquo;e-mails directement depuis ServiceNow <a href=\"https:\/\/developers.retarus.com\/docs\/transactional-email\/api\/sending-email\/\">par API<\/a> via notre solution performante en conformit\u00e9 totale avec le RGPD, le <a href=\"https:\/\/www.retarus.com\/fr\/enterprise-cloud\/\">Retarus Enterprise Cloud<\/a>, sans alourdir votre propre infrastructure de messagerie, ni celle de votre client. Avec une capacit\u00e9 garantie contractuellement par le biais d&rsquo;accords de niveau de service et gr\u00e2ce \u00e0 la certification&nbsp;CSA et \u00e0 une gestion sophistiqu\u00e9e de la r\u00e9putation, les taux de distribution sont excellents.<\/p>   <p>Retarus traite vos donn\u00e9es localement au sein de ses propres datacenters, lesquels sont certifi\u00e9s conformes aux normes de s\u00e9curit\u00e9 les plus exigeantes, notamment SOC 1, SOC 2 <a href=\"https:\/\/www.retarus.com\/blog\/fr\/retarus-est-certifie-iso-27001\/\">et ISO 27001<\/a>.<\/p>   <p>Cette infrastructure haut de gamme est compl\u00e9t\u00e9e par des outils complets de suivi et de g\u00e9n\u00e9ration de rapports, ainsi que par des fonctions de recherche sophistiqu\u00e9es permettant par exemple aux employ\u00e9s du centre d&rsquo;assistance ou du centre de contact de retrouver rapidement les e-mails transactionnels perdus et de les renvoyer sans devoir acc\u00e9der \u00e0 l&rsquo;application professionnelle qui les a envoy\u00e9s.<\/p>   <p>Bien entendu, les services de Retarus ne repr\u00e9sentent pas uniquement une valeur ajout\u00e9e pour vous et vos clients dans le contexte de ServiceNow. Vous pouvez bien s\u00fbr tout aussi bien en profiter pour reproduire de mani\u00e8re fiable, s\u00e9curis\u00e9e et \u00e9volutive les \u00ab&nbsp;20&nbsp;% restants&nbsp;\u00bb du flux de messagerie d&rsquo;applications telles que SAP et Salesforce ou de logiciels d&rsquo;automatisation marketing d&rsquo;outils comme Eloqua et Marketo.<\/p> ","protected":false},"excerpt":{"rendered":"<p>De nombreuses entreprises externalisent l&rsquo;int\u00e9gralit\u00e9 de l&rsquo;exploitation de ServiceNow aupr\u00e8s d&rsquo;int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s&rsquo;av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d&rsquo;envoi\u2026<\/p>\n","protected":false},"author":84,"featured_media":7900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8,3795,9],"tags":[2982],"class_list":["post-7503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-partners","category-product-news","tag-transactional-email"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&#039;e-mails depuis ServiceNow - Retarus Corporate Blog - FR<\/title>\n<meta name=\"description\" content=\"De nombreuses entreprises externalisent l&#039;int\u00e9gralit\u00e9 de l&#039;exploitation de ServiceNow aupr\u00e8s d&#039;int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s&#039;av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d&#039;envoi\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&#039;e-mails depuis ServiceNow\" \/>\n<meta property=\"og:description\" content=\"De nombreuses entreprises externalisent l&#039;int\u00e9gralit\u00e9 de l&#039;exploitation de ServiceNow aupr\u00e8s d&#039;int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s&#039;av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d&#039;envoi\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/\" \/>\n<meta property=\"og:site_name\" content=\"Retarus Corporate Blog - FR\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T12:42:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T17:46:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2024\/05\/shutterstock_1483041302.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Sch\u00e4fer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Sch\u00e4fer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/\"},\"author\":{\"name\":\"Nicolas Sch\u00e4fer\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/cb43642975e66f524e6b0c91a2eeb8d7\"},\"headline\":\"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&rsquo;e-mails depuis ServiceNow\",\"datePublished\":\"2023-09-14T12:42:02+00:00\",\"dateModified\":\"2024-05-07T17:46:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/\"},\"wordCount\":998,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/05\\\/shutterstock_1483041302.jpg\",\"keywords\":[\"Transactional Email\"],\"articleSection\":[\"News\",\"Partner\",\"Product News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/\",\"name\":\"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d'e-mails depuis ServiceNow - Retarus Corporate Blog - FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/05\\\/shutterstock_1483041302.jpg\",\"datePublished\":\"2023-09-14T12:42:02+00:00\",\"dateModified\":\"2024-05-07T17:46:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/cb43642975e66f524e6b0c91a2eeb8d7\"},\"description\":\"De nombreuses entreprises externalisent l'int\u00e9gralit\u00e9 de l'exploitation de ServiceNow aupr\u00e8s d'int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s'av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d'envoi\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/05\\\/shutterstock_1483041302.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/05\\\/shutterstock_1483041302.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Hand of man drowning in red like symbols and speech bubbles. Concept of social media addiction and too much virtual life.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&#8217;e-mails depuis ServiceNow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/\",\"name\":\"Retarus Corporate Blog - FR\",\"description\":\"Restez inform\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/#\\\/schema\\\/person\\\/cb43642975e66f524e6b0c91a2eeb8d7\",\"name\":\"Nicolas Sch\u00e4fer\",\"url\":\"https:\\\/\\\/www.retarus.com\\\/blog\\\/fr\\\/author\\\/nicolass\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d'e-mails depuis ServiceNow - Retarus Corporate Blog - FR","description":"De nombreuses entreprises externalisent l'int\u00e9gralit\u00e9 de l'exploitation de ServiceNow aupr\u00e8s d'int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s'av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d'envoi\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/","og_locale":"fr_FR","og_type":"article","og_title":"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d'e-mails depuis ServiceNow","og_description":"De nombreuses entreprises externalisent l'int\u00e9gralit\u00e9 de l'exploitation de ServiceNow aupr\u00e8s d'int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s'av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d'envoi\u2026","og_url":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/","og_site_name":"Retarus Corporate Blog - FR","article_published_time":"2023-09-14T12:42:02+00:00","article_modified_time":"2024-05-07T17:46:43+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2024\/05\/shutterstock_1483041302.jpg","type":"image\/jpeg"}],"author":"Nicolas Sch\u00e4fer","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicolas Sch\u00e4fer","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#article","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/"},"author":{"name":"Nicolas Sch\u00e4fer","@id":"https:\/\/www.retarus.com\/blog\/fr\/#\/schema\/person\/cb43642975e66f524e6b0c91a2eeb8d7"},"headline":"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&rsquo;e-mails depuis ServiceNow","datePublished":"2023-09-14T12:42:02+00:00","dateModified":"2024-05-07T17:46:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/"},"wordCount":998,"commentCount":0,"image":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2024\/05\/shutterstock_1483041302.jpg","keywords":["Transactional Email"],"articleSection":["News","Partner","Product News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/","url":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/","name":"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d'e-mails depuis ServiceNow - Retarus Corporate Blog - FR","isPartOf":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#primaryimage"},"image":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2024\/05\/shutterstock_1483041302.jpg","datePublished":"2023-09-14T12:42:02+00:00","dateModified":"2024-05-07T17:46:43+00:00","author":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/#\/schema\/person\/cb43642975e66f524e6b0c91a2eeb8d7"},"description":"De nombreuses entreprises externalisent l'int\u00e9gralit\u00e9 de l'exploitation de ServiceNow aupr\u00e8s d'int\u00e9grateurs syst\u00e8mes et de fournisseurs de services g\u00e9r\u00e9s. ServiceNow g\u00e9n\u00e8re cependant un flux de messagerie interne cons\u00e9quent, ce qui peut s'av\u00e9rer probl\u00e9matique pour une infrastructure de messagerie bas\u00e9e sur le cloud avec limites d'envoi\u2026","breadcrumb":{"@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#primaryimage","url":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2024\/05\/shutterstock_1483041302.jpg","contentUrl":"https:\/\/www.retarus.com\/blog\/fr\/wp-content\/uploads\/sites\/24\/2024\/05\/shutterstock_1483041302.jpg","width":1920,"height":1080,"caption":"Hand of man drowning in red like symbols and speech bubbles. Concept of social media addiction and too much virtual life."},{"@type":"BreadcrumbList","@id":"https:\/\/www.retarus.com\/blog\/fr\/service-wow-envoi-automatise-de-grands-volumes-d-e-mails-depuis-servicenow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retarus.com\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Service Wow\u00a0! Envoi automatis\u00e9 de grands volumes d&#8217;e-mails depuis ServiceNow"}]},{"@type":"WebSite","@id":"https:\/\/www.retarus.com\/blog\/fr\/#website","url":"https:\/\/www.retarus.com\/blog\/fr\/","name":"Retarus Corporate Blog - FR","description":"Restez inform\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retarus.com\/blog\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.retarus.com\/blog\/fr\/#\/schema\/person\/cb43642975e66f524e6b0c91a2eeb8d7","name":"Nicolas Sch\u00e4fer","url":"https:\/\/www.retarus.com\/blog\/fr\/author\/nicolass\/"}]}},"_links":{"self":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/7503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=7503"}],"version-history":[{"count":6,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/7503\/revisions"}],"predecessor-version":[{"id":9064,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/7503\/revisions\/9064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/media\/7900"}],"wp:attachment":[{"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=7503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=7503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retarus.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=7503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}